{"id":262506,"date":"2026-04-21T13:58:47","date_gmt":"2026-04-21T13:58:47","guid":{"rendered":"https:\/\/my.legal500.com\/events\/?page_id=262506"},"modified":"2026-04-21T16:46:10","modified_gmt":"2026-04-21T16:46:10","slug":"2025-celebration","status":"publish","type":"page","link":"https:\/\/my.legal500.com\/events\/canadian-in-house-counsel-celebration-2026\/2025-celebration\/","title":{"rendered":"2025 Celebration"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-262506 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-2_IHLAG154-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-2_IHLAG154-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG128-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG128-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG131-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG131-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG133-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG133-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG136-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG136-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG138-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG138-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG141-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG141-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG144-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG144-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG145-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG145-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG153-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG153-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG169-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG169-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG170-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG170-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG172-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG172-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG192-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG192-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG196-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG196-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG200-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG200-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG201-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG201-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG203-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG203-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG223-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG223-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG240-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG240-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG241-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG241-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG242-272x182-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG242-272x182-2.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG243-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG243-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG244-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG244-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG245-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG245-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG246-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG246-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG247-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG247-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG249-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG249-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG250-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG250-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG251-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG251-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG252-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG252-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG254-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG254-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG255-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG255-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG262-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG262-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG276-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG276-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG285-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG285-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG292-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG292-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG297-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG297-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG301-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG301-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG302-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG302-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG304-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG304-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG305-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG305-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG306-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG306-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG307-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG307-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG312-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG312-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG313-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG313-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG316-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG316-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG320-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG320-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG323-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG323-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG324-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG324-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG330-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG330-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG342-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG342-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG350-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG350-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG354-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG354-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG355-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG355-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG356-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG356-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG357-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG357-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG360-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG360-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG361-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG361-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG366-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG366-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG371-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG371-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG372-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG372-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG373-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG373-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG386-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG386-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG390-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG390-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG393-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG393-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG415-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG415-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG417-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG417-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG422-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG422-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG423-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG423-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG489-272x182-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"182\" src=\"https:\/\/my.legal500.com\/events\/wp-content\/uploads\/sites\/5\/2026\/04\/celebration_2025-IHLAG489-272x182-2.jpg\" class=\"attachment-medium size-medium\" alt=\"\" sizes=\"auto, 100vw\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":30,"featured_media":0,"parent":261768,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-262506","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/pages\/262506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/comments?post=262506"}],"version-history":[{"count":1,"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/pages\/262506\/revisions"}],"predecessor-version":[{"id":263080,"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/pages\/262506\/revisions\/263080"}],"up":[{"embeddable":true,"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/pages\/261768"}],"wp:attachment":[{"href":"https:\/\/my.legal500.com\/events\/wp-json\/wp\/v2\/media?parent=262506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}