{"id":50678,"date":"2025-07-31T08:15:35","date_gmt":"2025-07-31T08:15:35","guid":{"rendered":"https:\/\/my.legal500.com\/developments\/?post_type=legal_developments&#038;p=50678"},"modified":"2025-07-31T08:15:35","modified_gmt":"2025-07-31T08:15:35","slug":"beccar-varela-incorpora-como-socia-a-jimena-vega-olmos","status":"publish","type":"legal_developments","link":"https:\/\/my.legal500.com\/developments\/thought-leadership\/beccar-varela-incorpora-como-socia-a-jimena-vega-olmos\/","title":{"rendered":"Beccar Varela incorpora como socia a Jimena Vega Olmos"},"content":{"rendered":"<p><strong>Buenos Aires, 29 de julio de 2025 \u2014 Beccar Varela anuncia la incorporaci\u00f3n de <a href=\"https:\/\/beccarvarela.com\/equipo\/jimena-vega-olmos\/\">Jimena Vega Olmos<\/a> como nueva socia del departamento de <a href=\"https:\/\/beccarvarela.com\/expertise\/areas\/energia\/\">Energ\u00eda<\/a>. Con una s\u00f3lida trayectoria de m\u00e1s de 20 a\u00f1os asesorando a clientes locales e internacionales en transacciones complejas y asuntos estrat\u00e9gicos vinculados a la energ\u00eda, infraestructura, financiamiento de proyectos y arbitraje de inversiones, su llegada fortalece un \u00e1rea clave de la pr\u00e1ctica del estudio. Jimena se suma a Ricardo Casta\u00f1eda, Pedro Silvestri y Carlos Cueva, socios del equipo de Energ\u00eda, aportando su conocimiento, su experiencia y su visi\u00f3n.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Antes de sumarse a Beccar Varela, Jimena fue socia de Mart\u00ednez de Hoz &amp; Rueda (2018\u20132025), firma a la que se uni\u00f3 tras una destacada trayectoria en P\u00e9rez Alati, Grondona, Benites &amp; Arntsen (1998\u20132017). Es abogada por la Universidad de Buenos Aires (2002), con una especializaci\u00f3n en Derecho Administrativo Econ\u00f3mico (2007), y ha completado una formaci\u00f3n ejecutiva en Infraestructura en una Econom\u00eda de Mercado en Harvard University (2017). Actualmente integra la mesa directiva de la Comisi\u00f3n Pro Bono del Colegio de Abogados de la Ciudad de Buenos Aires.<\/p>\n<p>Maximiliano D&#8217;Auro, socio administrador de Beccar Varela, expres\u00f3: \u201cEstamos muy entusiasmados con la incorporaci\u00f3n de Jimena. Quienes hemos tenido la oportunidad de interactuar con ella a lo largo de nuestra vida profesional, sabemos que es una abogada excepcional, adem\u00e1s de una gran persona. Confiamos en que su experiencia va a aportar gran valor al desarrollo de nuestra pr\u00e1ctica de Energ\u00eda, una de las \u00e1reas estrat\u00e9gicas para el crecimiento del estudio y del pa\u00eds\u201d.<\/p>\n<p>Los socios de Mart\u00ednez de Hoz &amp; Rueda expresaron su reconocimiento por la contribuci\u00f3n de Jimena durante su paso por la firma: \u201cJimena ha sido una parte importante de nuestro equipo desde el inicio. Es una gran satisfacci\u00f3n para MHR haberla acompa\u00f1ado en su crecimiento profesional. Valoraremos siempre su aporte y agradecemos profundamente su compromiso, dese\u00e1ndole \u00e9xito en su nueva etapa\u201d, manifest\u00f3 Jos\u00e9 Mart\u00ednez de Hoz. Asimismo, Pablo Rueda, coment\u00f3: \u201cJimena ser\u00e1 extra\u00f1ada por todo MHR. No obstante, este cambio es parte de la evoluci\u00f3n de la firma, y en MHR continuamos con nuestros planes de crecimiento y apostando a seguir brindando el servicio de excelencia al que nuestros clientes est\u00e1n acostumbrados desde una plataforma que maximiza las oportunidades de crecimiento profesional de nuestros abogados.\u201d<\/p>\n<p>Por su parte, Jimena Vega Olmos afirm\u00f3: \u201cEstoy muy contenta de sumarme a Beccar Varela. A lo largo de los a\u00f1os he tenido la oportunidad de compartir con algunos miembros de su equipo distintos espacios profesionales. Admiro su trayectoria, su enfoque innovador y su compromiso con el desarrollo integral del pa\u00eds. Espero contribuir con mi experiencia al crecimiento de la pr\u00e1ctica y a los desaf\u00edos que plantea el sector energ\u00e9tico\u201d.<\/p>\n<p>Jimena se incorpora en un momento clave para la pr\u00e1ctica de Energ\u00eda de Beccar Varela, que contin\u00faa consolidando su presencia en un sector central para el desarrollo econ\u00f3mico, social y ambiental de la Argentina.<\/p>\n<p><strong>Acerca de Beccar Varela<\/strong><\/p>\n<p>Beccar Varela es un estudio jur\u00eddico l\u00edder de Argentina fundado en 1897, reconocido por brindar asesoramiento legal integral de excelencia tanto a empresas nacionales como internacionales. Con un enfoque innovador, su equipo est\u00e1 conformado por m\u00e1s de 160 abogados altamente capacitados y comprometidos con los valores de integridad, profesionalismo, respeto, diversidad y responsabilidad social. Con sede principal en la Ciudad de Buenos Aires, cuenta adem\u00e1s con oficinas en Tigre, provincia de Buenos Aires, y en la Zona Franca de Montevideo, Uruguay. Beccar Varela combina una s\u00f3lida experiencia local con una visi\u00f3n global.\u00b7<\/p>\n<p><a href=\"http:\/\/www.beccarvarela.com\">www.beccarvarela.com<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50682\" src=\"https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-300x300.jpg 300w, https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-1024x1024.jpg 1024w, https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-150x150.jpg 150w, https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-768x768.jpg 768w, https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-1536x1536.jpg 1536w, https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-2048x2048.jpg 2048w, https:\/\/my.legal500.com\/developments\/wp-content\/uploads\/sites\/19\/2025\/07\/Jimena-Vega-Olmos_Beccar-Varela-100x100.jpg 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-50678","legal_developments","type-legal_developments","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/my.legal500.com\/developments\/wp-json\/wp\/v2\/legal_developments\/50678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my.legal500.com\/developments\/wp-json\/wp\/v2\/legal_developments"}],"about":[{"href":"https:\/\/my.legal500.com\/developments\/wp-json\/wp\/v2\/types\/legal_developments"}],"wp:attachment":[{"href":"https:\/\/my.legal500.com\/developments\/wp-json\/wp\/v2\/media?parent=50678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}